{"id":109,"count":1,"description":"","link":"https:\/\/blog.nautal.com\/it\/tag\/noleggio-barca\/","name":"noleggio barca","slug":"noleggio-barca","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>noleggio barca - Il blog Nautal | Tutte le informazioni sul noleggio di barche<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"noleggio barca - Il blog Nautal | Tutte le informazioni sul noleggio di barche\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.nautal.com\/it\/tag\/noleggio-barca\/\" \/>\n<meta property=\"og:site_name\" content=\"Il blog Nautal | Tutte le informazioni sul noleggio di barche\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ClickandBoat\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.nautal.com\/it\/tag\/noleggio-barca\/\",\"url\":\"https:\/\/blog.nautal.com\/it\/tag\/noleggio-barca\/\",\"name\":\"noleggio barca - Il blog Nautal | Tutte le informazioni sul noleggio di barche\",\"isPartOf\":{\"@id\":\"https:\/\/blog.nautal.com\/it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.nautal.com\/it\/tag\/noleggio-barca\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.nautal.com\/it\/tag\/noleggio-barca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\/\/blog.nautal.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"noleggio barca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.nautal.com\/it\/#website\",\"url\":\"https:\/\/blog.nautal.com\/it\/\",\"name\":\"Il blog Nautal | Tutte le informazioni sul noleggio di barche\",\"description\":\"Ora la vela \u00e8 alla portata di tutti!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.nautal.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"noleggio barca - Il blog Nautal | Tutte le informazioni sul noleggio di barche","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"noleggio barca - Il blog Nautal | Tutte le informazioni sul noleggio di barche","og_url":"https:\/\/blog.nautal.com\/it\/tag\/noleggio-barca\/","og_site_name":"Il blog Nautal | Tutte le informazioni sul noleggio di barche","twitter_card":"summary_large_image","twitter_site":"@ClickandBoat","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.nautal.com\/it\/tag\/noleggio-barca\/","url":"https:\/\/blog.nautal.com\/it\/tag\/noleggio-barca\/","name":"noleggio barca - Il blog Nautal | Tutte le informazioni sul noleggio di barche","isPartOf":{"@id":"https:\/\/blog.nautal.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/blog.nautal.com\/it\/tag\/noleggio-barca\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.nautal.com\/it\/tag\/noleggio-barca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/blog.nautal.com\/it\/"},{"@type":"ListItem","position":2,"name":"noleggio barca"}]},{"@type":"WebSite","@id":"https:\/\/blog.nautal.com\/it\/#website","url":"https:\/\/blog.nautal.com\/it\/","name":"Il blog Nautal | Tutte le informazioni sul noleggio di barche","description":"Ora la vela \u00e8 alla portata di tutti!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.nautal.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/blog.nautal.com\/it\/wp-json\/wp\/v2\/tags\/109"}],"collection":[{"href":"https:\/\/blog.nautal.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.nautal.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.nautal.com\/it\/wp-json\/wp\/v2\/posts?tags=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}