{"id":1,"date":"2013-08-05T09:19:42","date_gmt":"2013-08-05T07:19:42","guid":{"rendered":"https:\/\/blog.nautal.com\/es\/blog\/?p=1"},"modified":"2023-02-21T10:17:50","modified_gmt":"2023-02-21T09:17:50","slug":"hola-navegantes","status":"publish","type":"post","link":"https:\/\/blog.nautal.com\/es\/hola-navegantes\/","title":{"rendered":"\u00a1Hola navegantes!"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00a1Hola Navegantes! Esta es la primera entrada en el blog de <a href=\"https:\/\/www.nautal.es\/\">Nautal\u00a0<\/a>y nuestro objetivo es el mismo por el que comenzamos a trabajar: queremos hacer m\u00e1s accesible el mundo de la n\u00e1utica.<\/p>\n<figure id=\"attachment_1454\" aria-describedby=\"caption-attachment-1454\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1454 size-medium\" src=\"https:\/\/blog.nautal.com\/es\/wp-content\/uploads\/2013\/08\/lancha-nautal-800x533.jpg\" alt=\"lanchas\" width=\"800\" height=\"533\" srcset=\"https:\/\/blog.nautal.com\/es\/wp-content\/uploads\/2013\/08\/lancha-nautal-800x533.jpg 800w, https:\/\/blog.nautal.com\/es\/wp-content\/uploads\/2013\/08\/lancha-nautal-320x213.jpg 320w, https:\/\/blog.nautal.com\/es\/wp-content\/uploads\/2013\/08\/lancha-nautal-560x373.jpg 560w, https:\/\/blog.nautal.com\/es\/wp-content\/uploads\/2013\/08\/lancha-nautal.jpg 868w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-1454\" class=\"wp-caption-text\">lancha nautal<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">En Espa\u00f1a hay m\u00e1s de 200 mil barcos repartidos en casi 8000 kil\u00f3metros de costa, pero los puertos acostumbran a estar llenos de barcos y vac\u00edos de gente. Se estima que un propietario usa su embarcaci\u00f3n menos de 20 d\u00edas al a\u00f1o de media.<\/p>\n<p style=\"text-align: justify;\"><span style=\"line-height: 1.5;\">Para ello, nuestra propuesta es que los <strong>armadores<\/strong>, los propietarios de barcos, disfruten de sus barcos siempre que quieran sin que les suponga una carga el mantenerlos. Trabajaremos a su lado, para hacerles f\u00e1cil este proceso y ayudarles a sacar el m\u00e1ximo partido de sus barcos.<\/span><\/p>\n<p style=\"text-align: justify;\">Para los <strong>clientes<\/strong>, queremos ofrecerles un medio econ\u00f3mico y flexible de acceder a la n\u00e1utica. Quien comienza en este mundo, generalmente no quiere alquilar una semana entera, quiere un d\u00eda o incluso medio d\u00eda y a un precio razonable.<\/p>\n<p style=\"text-align: justify;\">Nuestro nombre \u00abNautal\u00bb sintetiza nuestro objetivo, que no es otro que todos podamos disfrutar del mar y la <strong>navegaci\u00f3n<\/strong> y en este blog iremos a\u00f1adiendo contenido para ayudar tanto a los propietarios de los barcos como a los clientes.<\/p>\n<ul>\n<li>\u00bfC\u00f3mo planificar una salida?<\/li>\n<li>\u00bfQu\u00e9 llevar a bordo?<\/li>\n<li>\u00bfC\u00f3mo hacer el check-in y el check-out?<\/li>\n<li>\u00bfC\u00f3mo actuar si hay un incidente durante el alquiler?<\/li>\n<li>\u00bfQu\u00e9 rentabilidad puedo obtener si alquilo?<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">A estas y a muchas otras preguntas iremos respondiendo desde este blog. No dudes a\u00f1adir en los comentarios \u00a0qu\u00e9 te gustar\u00eda que trat\u00e1ramos.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">\u00a1Hola Navegantes! Esta es la primera entrada en el blog de Nautal\u00a0y nuestro objetivo es el mismo por el que comenzamos a trabajar: queremos hacer m\u00e1s accesible el mundo de&hellip;<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/blog.nautal.com\/es\/hola-navegantes\/\" class=\"button button-primary button-effect\"><span>LEER M\u00c1S<\/span><span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":31,"featured_media":1454,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a1Hola navegantes! Blog de Nautal\u00a0<\/title>\n<meta name=\"description\" content=\"\u00a1Hola navegantes! Os presentamos el blog de Nautal\u00a0. Nuestro objetivo es hacer m\u00e1s accesible el mundo de la n\u00e1utica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.nautal.com\/es\/hola-navegantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Hola navegantes! Blog de Nautal\u00a0\" \/>\n<meta property=\"og:description\" content=\"\u00a1Hola navegantes! Os presentamos el blog de Nautal\u00a0. Nuestro objetivo es hacer m\u00e1s accesible el mundo de la n\u00e1utica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.nautal.com\/es\/hola-navegantes\/\" \/>\n<meta property=\"og:site_name\" content=\"El blog de Nautal | Toda la informaci\u00f3n sobre el alquiler de barcos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ClickandboatEN\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-05T07:19:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-21T09:17:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.nautal.com\/es\/wp-content\/uploads\/2013\/08\/lancha-nautal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"868\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Berta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ClickandBoat\" \/>\n<meta name=\"twitter:site\" content=\"@ClickandBoat\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Berta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.nautal.com\/es\/hola-navegantes\/\",\"url\":\"https:\/\/blog.nautal.com\/es\/hola-navegantes\/\",\"name\":\"\u00a1Hola navegantes! Blog de Nautal\u00a0\",\"isPartOf\":{\"@id\":\"https:\/\/blog.nautal.com\/es\/#website\"},\"datePublished\":\"2013-08-05T07:19:42+00:00\",\"dateModified\":\"2023-02-21T09:17:50+00:00\",\"author\":{\"@id\":\"https:\/\/blog.nautal.com\/es\/#\/schema\/person\/97d72e5d95c051f76cc281765a684936\"},\"description\":\"\u00a1Hola navegantes! Os presentamos el blog de Nautal\u00a0. Nuestro objetivo es hacer m\u00e1s accesible el mundo de la n\u00e1utica.\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.nautal.com\/es\/hola-navegantes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.nautal.com\/es\/hola-navegantes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.nautal.com\/es\/hola-navegantes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\/\/blog.nautal.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Hola navegantes!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.nautal.com\/es\/#website\",\"url\":\"https:\/\/blog.nautal.com\/es\/\",\"name\":\"El blog de Nautal | Toda la informaci\u00f3n sobre el alquiler de barcos\",\"description\":\"Ahora la navegaci\u00f3n est\u00e1 al alcance de todos.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.nautal.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.nautal.com\/es\/#\/schema\/person\/97d72e5d95c051f76cc281765a684936\",\"name\":\"Berta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blog.nautal.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b673f23c5f2bbfa5f5769722f63bbe11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b673f23c5f2bbfa5f5769722f63bbe11?s=96&d=mm&r=g\",\"caption\":\"Berta\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Hola navegantes! Blog de Nautal\u00a0","description":"\u00a1Hola navegantes! Os presentamos el blog de Nautal\u00a0. Nuestro objetivo es hacer m\u00e1s accesible el mundo de la n\u00e1utica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.nautal.com\/es\/hola-navegantes\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Hola navegantes! Blog de Nautal\u00a0","og_description":"\u00a1Hola navegantes! Os presentamos el blog de Nautal\u00a0. Nuestro objetivo es hacer m\u00e1s accesible el mundo de la n\u00e1utica.","og_url":"https:\/\/blog.nautal.com\/es\/hola-navegantes\/","og_site_name":"El blog de Nautal | Toda la informaci\u00f3n sobre el alquiler de barcos","article_publisher":"https:\/\/www.facebook.com\/ClickandboatEN\/","article_published_time":"2013-08-05T07:19:42+00:00","article_modified_time":"2023-02-21T09:17:50+00:00","og_image":[{"width":868,"height":578,"url":"https:\/\/blog.nautal.com\/es\/wp-content\/uploads\/2013\/08\/lancha-nautal.jpg","type":"image\/jpeg"}],"author":"Berta","twitter_card":"summary_large_image","twitter_creator":"@ClickandBoat","twitter_site":"@ClickandBoat","twitter_misc":{"Written by":"Berta","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.nautal.com\/es\/hola-navegantes\/","url":"https:\/\/blog.nautal.com\/es\/hola-navegantes\/","name":"\u00a1Hola navegantes! Blog de Nautal\u00a0","isPartOf":{"@id":"https:\/\/blog.nautal.com\/es\/#website"},"datePublished":"2013-08-05T07:19:42+00:00","dateModified":"2023-02-21T09:17:50+00:00","author":{"@id":"https:\/\/blog.nautal.com\/es\/#\/schema\/person\/97d72e5d95c051f76cc281765a684936"},"description":"\u00a1Hola navegantes! Os presentamos el blog de Nautal\u00a0. Nuestro objetivo es hacer m\u00e1s accesible el mundo de la n\u00e1utica.","breadcrumb":{"@id":"https:\/\/blog.nautal.com\/es\/hola-navegantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.nautal.com\/es\/hola-navegantes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.nautal.com\/es\/hola-navegantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/blog.nautal.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00a1Hola navegantes!"}]},{"@type":"WebSite","@id":"https:\/\/blog.nautal.com\/es\/#website","url":"https:\/\/blog.nautal.com\/es\/","name":"El blog de Nautal | Toda la informaci\u00f3n sobre el alquiler de barcos","description":"Ahora la navegaci\u00f3n est\u00e1 al alcance de todos.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.nautal.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blog.nautal.com\/es\/#\/schema\/person\/97d72e5d95c051f76cc281765a684936","name":"Berta","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.nautal.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b673f23c5f2bbfa5f5769722f63bbe11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b673f23c5f2bbfa5f5769722f63bbe11?s=96&d=mm&r=g","caption":"Berta"}}]}},"_links":{"self":[{"href":"https:\/\/blog.nautal.com\/es\/wp-json\/wp\/v2\/posts\/1"}],"collection":[{"href":"https:\/\/blog.nautal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.nautal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.nautal.com\/es\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.nautal.com\/es\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":1,"href":"https:\/\/blog.nautal.com\/es\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":6707,"href":"https:\/\/blog.nautal.com\/es\/wp-json\/wp\/v2\/posts\/1\/revisions\/6707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.nautal.com\/es\/wp-json\/wp\/v2\/media\/1454"}],"wp:attachment":[{"href":"https:\/\/blog.nautal.com\/es\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.nautal.com\/es\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.nautal.com\/es\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}